{"id":337,"date":"2020-11-26T10:32:34","date_gmt":"2020-11-26T15:32:34","guid":{"rendered":"http:\/\/youngcaregiversconnect.ca\/stories\/sarahs-story\/"},"modified":"2021-03-25T15:47:22","modified_gmt":"2021-03-25T19:47:22","slug":"je-suis-daniel-et-je-moccupe-de-mes-freres","status":"publish","type":"story","link":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/","title":{"rendered":"Je suis Daniel et je m\u2019occupe de mes fr\u00e8res"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">J\u2019imagine que j\u2019ai toujours \u00e9t\u00e9 un aidant naturel, je suppose. J\u2019ai deux fr\u00e8res qui sont atteints d\u2019autisme. Si tu as d\u00e9j\u00e0 eu une telle exp\u00e9rience, tu sais bien que c\u2019est toute la journ\u00e9e, tous les jours. Mon r\u00f4le d\u2019aidant a pris une plus grande importance quand j\u2019avais environ 16 ans et que ma m\u00e8re a eu un terrible accident \u00e0 la suite duquel elle avait besoin d\u2019aide. Certains des d\u00e9fis auxquels font face les jeunes aidants naturels sont le manque d\u2019information ou d\u2019explications. La fa\u00e7on dont j\u2019ai surmont\u00e9 certaines de ces difficult\u00e9s c\u2019est que je suis all\u00e9 \u00e0 l\u2019universit\u00e9 pour devenir travailleur des services aux enfants et \u00e0 la jeunesse. Je suis devenu un professionnel pour obtenir cette explication et fournir ce soutien \u00e0 la maison. La formation \u00e0 l\u2019\u00e9cole te permet d\u2019apprendre tout sur l\u2019importance de prendre soin de toi. Une des choses qui fonctionne le mieux pour moi, c\u2019est de me retirer. Je me d\u00e9tache de tout avec une tasse de th\u00e9 et un livre. Mon temps est vraiment important.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de prendre du temps pour soi, mon meilleur conseil \u00e0 un jeune aidant naturel est de trouver diff\u00e9rentes ressources et de ne pas accepter qu\u2019on lui dise, \u00ab&nbsp;tu n\u2019as pas besoin de savoir \u00e7a&nbsp;\u00bb.<\/p>\n\n\n<div id=\"intext-quote-block_5fd826c446ac5\" class=\"intext-quote \">\n    <div class=\"row\">\n                <div class=\"large-6 column\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"542\" height=\"316\" src=\"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/11\/Daniel.jpg\" class=\"attachment-box-image size-box-image\" alt=\"Daniel\" srcset=\"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/11\/Daniel.jpg 542w, https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/11\/Daniel-300x175.jpg 300w\" sizes=\"auto, (max-width: 542px) 100vw, 542px\" \/>        <\/div>\n                <div class=\"large-6 column\">\n            <div class=\"quote\">\n                <div class=\"text\">N\u2019accepte pas qu\u2019on te dise \u00ab tu n\u2019as pas besoin de savoir \u00e7a \u00bb.<\/div>\n                <div class=\"name\">Daniel<\/div>\n                <div class=\"title\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>J\u2019ai toujours \u00e9t\u00e9 un aidant naturel, je suppose. J\u2019ai deux fr\u00e8res qui sont autistes. Si tu as d\u00e9j\u00e0 eu une telle exp\u00e9rience, alors tu sais, c\u2019est toute la journ\u00e9e, tous les jours. Mon r\u00f4le d\u2019aidant a pris une plus grande importance quand j\u2019avais environ 16 ans et que ma m\u00e8re a eu un terrible accident \u00e0 la suite duquel elle avait besoin d\u2019aide. Certains des d\u00e9fis auxquels font face les jeunes aidants naturels sont le manque d\u2019information et d\u2019explications. La fa\u00e7on dont j\u2019ai surmont\u00e9 certaines de ces difficult\u00e9s c\u2019est que je suis all\u00e9 \u00e0 l\u2019universit\u00e9 pour devenir travailleur des services aux enfants et \u00e0 la jeunesse. <\/p>\n","protected":false},"author":1,"featured_media":762,"menu_order":0,"template":"","class_list":["post-337","story","type-story","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Je suis Daniel et je m\u2019occupe de mes fr\u00e8res - Young Caregivers Connect<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Je suis Daniel et je m\u2019occupe de mes fr\u00e8res - Young Caregivers Connect\" \/>\n<meta property=\"og:description\" content=\"J\u2019ai toujours \u00e9t\u00e9 un aidant naturel, je suppose. J\u2019ai deux fr\u00e8res qui sont autistes. Si tu as d\u00e9j\u00e0 eu une telle exp\u00e9rience, alors tu sais, c\u2019est toute la journ\u00e9e, tous les jours. Mon r\u00f4le d\u2019aidant a pris une plus grande importance quand j\u2019avais environ 16 ans et que ma m\u00e8re a eu un terrible accident \u00e0 la suite duquel elle avait besoin d\u2019aide. Certains des d\u00e9fis auxquels font face les jeunes aidants naturels sont le manque d\u2019information et d\u2019explications. La fa\u00e7on dont j\u2019ai surmont\u00e9 certaines de ces difficult\u00e9s c\u2019est que je suis all\u00e9 \u00e0 l\u2019universit\u00e9 pour devenir travailleur des services aux enfants et \u00e0 la jeunesse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/\" \/>\n<meta property=\"og:site_name\" content=\"Young Caregivers Connect\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-25T19:47:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/11\/Daniel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"542\" \/>\n\t<meta property=\"og:image:height\" content=\"316\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/histoires\\\/je-suis-daniel-et-je-moccupe-de-mes-freres\\\/\",\"url\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/histoires\\\/je-suis-daniel-et-je-moccupe-de-mes-freres\\\/\",\"name\":\"Je suis Daniel et je m\u2019occupe de mes fr\u00e8res - Young Caregivers Connect\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/histoires\\\/je-suis-daniel-et-je-moccupe-de-mes-freres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/histoires\\\/je-suis-daniel-et-je-moccupe-de-mes-freres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Daniel.jpg\",\"datePublished\":\"2020-11-26T15:32:34+00:00\",\"dateModified\":\"2021-03-25T19:47:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/histoires\\\/je-suis-daniel-et-je-moccupe-de-mes-freres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/histoires\\\/je-suis-daniel-et-je-moccupe-de-mes-freres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/histoires\\\/je-suis-daniel-et-je-moccupe-de-mes-freres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Daniel.jpg\",\"contentUrl\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Daniel.jpg\",\"width\":542,\"height\":316,\"caption\":\"Daniel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/histoires\\\/je-suis-daniel-et-je-moccupe-de-mes-freres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoires\",\"item\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/histoires\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Je suis Daniel et je m\u2019occupe de mes fr\u00e8res\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/#website\",\"url\":\"http:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/\",\"name\":\"Young Caregivers Connect\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Je suis Daniel et je m\u2019occupe de mes fr\u00e8res - Young Caregivers Connect","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/","og_locale":"fr_FR","og_type":"article","og_title":"Je suis Daniel et je m\u2019occupe de mes fr\u00e8res - Young Caregivers Connect","og_description":"J\u2019ai toujours \u00e9t\u00e9 un aidant naturel, je suppose. J\u2019ai deux fr\u00e8res qui sont autistes. Si tu as d\u00e9j\u00e0 eu une telle exp\u00e9rience, alors tu sais, c\u2019est toute la journ\u00e9e, tous les jours. Mon r\u00f4le d\u2019aidant a pris une plus grande importance quand j\u2019avais environ 16 ans et que ma m\u00e8re a eu un terrible accident \u00e0 la suite duquel elle avait besoin d\u2019aide. Certains des d\u00e9fis auxquels font face les jeunes aidants naturels sont le manque d\u2019information et d\u2019explications. La fa\u00e7on dont j\u2019ai surmont\u00e9 certaines de ces difficult\u00e9s c\u2019est que je suis all\u00e9 \u00e0 l\u2019universit\u00e9 pour devenir travailleur des services aux enfants et \u00e0 la jeunesse.","og_url":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/","og_site_name":"Young Caregivers Connect","article_modified_time":"2021-03-25T19:47:22+00:00","og_image":[{"width":542,"height":316,"url":"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/11\/Daniel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/","url":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/","name":"Je suis Daniel et je m\u2019occupe de mes fr\u00e8res - Young Caregivers Connect","isPartOf":{"@id":"http:\/\/youngcaregiversconnect.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/#primaryimage"},"image":{"@id":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/#primaryimage"},"thumbnailUrl":"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/11\/Daniel.jpg","datePublished":"2020-11-26T15:32:34+00:00","dateModified":"2021-03-25T19:47:22+00:00","breadcrumb":{"@id":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/#primaryimage","url":"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/11\/Daniel.jpg","contentUrl":"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/11\/Daniel.jpg","width":542,"height":316,"caption":"Daniel"},{"@type":"BreadcrumbList","@id":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/je-suis-daniel-et-je-moccupe-de-mes-freres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/youngcaregiversconnect.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Histoires","item":"https:\/\/youngcaregiversconnect.ca\/fr\/histoires\/"},{"@type":"ListItem","position":3,"name":"Je suis Daniel et je m\u2019occupe de mes fr\u00e8res"}]},{"@type":"WebSite","@id":"http:\/\/youngcaregiversconnect.ca\/fr\/#website","url":"http:\/\/youngcaregiversconnect.ca\/fr\/","name":"Young Caregivers Connect","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/youngcaregiversconnect.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/story\/337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/media\/762"}],"wp:attachment":[{"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/media?parent=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}