{"id":323,"date":"2020-12-22T22:56:59","date_gmt":"2020-12-23T03:56:59","guid":{"rendered":"http:\/\/youngcaregiversconnect.ca\/tips\/tips-for-school-staff\/"},"modified":"2021-04-07T14:12:12","modified_gmt":"2021-04-07T18:12:12","slug":"conseils-pour-le-personnel-des-ecoles","status":"publish","type":"tip","link":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/","title":{"rendered":"Conseils pour le personnel des \u00e9coles"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019\u00e9cole est un des rares endroits o\u00f9 un jeune aidant naturel n\u2019est pas devant ses responsabilit\u00e9s ou son stress, et vous \u00eates peut-\u00eatre le seul adulte en dehors de sa famille \u00e0 qui il peut faire confiance et se confier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong>Voici quelques fa\u00e7ons dont vous pouvez lui apporter votre soutien\u00a0\u00a0:<\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>D\u00e9veloppez un lien de confiance &#8211; dites-lui qu\u2019il peut vous parler de tout<\/li><li>Concentrez-vous sur ses exp\u00e9riences et ses sentiments au lieu du proche dont il est responsable<\/li><li>Assurez-vous de bien comprendre le r\u00f4le qu\u2019il veut que vous jouiez &#8211; a-t-il besoin de quelqu\u2019un qui l\u2019\u00e9coute sans le juger? Ou bien cherche-t-il un mentor?<\/li><li>Pr\u00e9voyez du temps dans votre horaire pour communiquer r\u00e9guli\u00e8rement avec le jeune aidant naturel<\/li><li>Faites preuve de souplesse et r\u00e9pondez \u00e0 ses besoins lorsque vous le pouvez<\/li><li>R\u00e9servez du temps en dehors des cours pour l\u2019aider \u00e0 faire ses devoirs<\/li><li>Accordez-lui des prolongations lorsque c\u2019est possible<\/li><li>Soyez compr\u00e9hensif lorsqu\u2019il manque l\u2019\u00e9cole pour aider sa famille<\/li><li>Trouvez des moyens de l\u2019aider \u00e0 rester en contact avec sa famille pendant les heures de classe<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019exercice sous presque toutes ses formes, que ce soit du yoga ou de la course, peut t\u2019aider \u00e0 g\u00e9rer ton stress. Lorsque tu es physiquement actif, ton corps lib\u00e8re des endorphines qui te font du bien. <\/p>\n","protected":false},"author":1,"featured_media":543,"menu_order":4,"template":"","section":[25,26],"class_list":["post-323","tip","type-tip","status-publish","has-post-thumbnail","hentry","section-conseils","section-conseils-pour-soutenir-les-aidants-naturels"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conseils pour le personnel des \u00e9coles - Young Caregivers Connect<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseils pour le personnel des \u00e9coles - Young Caregivers Connect\" \/>\n<meta property=\"og:description\" content=\"L\u2019exercice sous presque toutes ses formes, que ce soit du yoga ou de la course, peut t\u2019aider \u00e0 g\u00e9rer ton stress. Lorsque tu es physiquement actif, ton corps lib\u00e8re des endorphines qui te font du bien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/\" \/>\n<meta property=\"og:site_name\" content=\"Young Caregivers Connect\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-07T18:12:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/12\/Tips-for-School-Staff-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/conseils\\\/conseils-pour-le-personnel-des-ecoles\\\/\",\"url\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/conseils\\\/conseils-pour-le-personnel-des-ecoles\\\/\",\"name\":\"Conseils pour le personnel des \u00e9coles - Young Caregivers Connect\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/conseils\\\/conseils-pour-le-personnel-des-ecoles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/conseils\\\/conseils-pour-le-personnel-des-ecoles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tips-for-School-Staff-scaled.jpg\",\"datePublished\":\"2020-12-23T03:56:59+00:00\",\"dateModified\":\"2021-04-07T18:12:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/conseils\\\/conseils-pour-le-personnel-des-ecoles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/conseils\\\/conseils-pour-le-personnel-des-ecoles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/conseils\\\/conseils-pour-le-personnel-des-ecoles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tips-for-School-Staff-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tips-for-School-Staff-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Business meeting\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/conseils\\\/conseils-pour-le-personnel-des-ecoles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils\",\"item\":\"https:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/conseils\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseils pour le personnel des \u00e9coles\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/#website\",\"url\":\"http:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/\",\"name\":\"Young Caregivers Connect\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/youngcaregiversconnect.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conseils pour le personnel des \u00e9coles - Young Caregivers Connect","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/","og_locale":"fr_FR","og_type":"article","og_title":"Conseils pour le personnel des \u00e9coles - Young Caregivers Connect","og_description":"L\u2019exercice sous presque toutes ses formes, que ce soit du yoga ou de la course, peut t\u2019aider \u00e0 g\u00e9rer ton stress. Lorsque tu es physiquement actif, ton corps lib\u00e8re des endorphines qui te font du bien.","og_url":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/","og_site_name":"Young Caregivers Connect","article_modified_time":"2021-04-07T18:12:12+00:00","og_image":[{"width":2560,"height":1707,"url":"http:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/12\/Tips-for-School-Staff-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/","url":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/","name":"Conseils pour le personnel des \u00e9coles - Young Caregivers Connect","isPartOf":{"@id":"http:\/\/youngcaregiversconnect.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/#primaryimage"},"image":{"@id":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/#primaryimage"},"thumbnailUrl":"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/12\/Tips-for-School-Staff-scaled.jpg","datePublished":"2020-12-23T03:56:59+00:00","dateModified":"2021-04-07T18:12:12+00:00","breadcrumb":{"@id":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/#primaryimage","url":"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/12\/Tips-for-School-Staff-scaled.jpg","contentUrl":"https:\/\/youngcaregiversconnect.ca\/wp-content\/uploads\/2020\/12\/Tips-for-School-Staff-scaled.jpg","width":2560,"height":1707,"caption":"Business meeting"},{"@type":"BreadcrumbList","@id":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/conseils-pour-le-personnel-des-ecoles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/youngcaregiversconnect.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Conseils","item":"https:\/\/youngcaregiversconnect.ca\/fr\/conseils\/"},{"@type":"ListItem","position":3,"name":"Conseils pour le personnel des \u00e9coles"}]},{"@type":"WebSite","@id":"http:\/\/youngcaregiversconnect.ca\/fr\/#website","url":"http:\/\/youngcaregiversconnect.ca\/fr\/","name":"Young Caregivers Connect","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/youngcaregiversconnect.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/tip\/323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/tip"}],"about":[{"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/types\/tip"}],"author":[{"embeddable":true,"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/media\/543"}],"wp:attachment":[{"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/media?parent=323"}],"wp:term":[{"taxonomy":"section","embeddable":true,"href":"https:\/\/youngcaregiversconnect.ca\/fr\/wp-json\/wp\/v2\/section?post=323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}